{"id":83382,"date":"2020-05-14T11:24:07","date_gmt":"2020-05-14T14:24:07","guid":{"rendered":"https:\/\/www.smart-gsm.com\/blog\/?p=83382"},"modified":"2020-05-14T11:24:24","modified_gmt":"2020-05-14T14:24:24","slug":"sony-anuncia-sony-imx500-imx501","status":"publish","type":"post","link":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/","title":{"rendered":"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presencia de <strong><a href=\"https:\/\/www.smart-gsm.com\/fabricantes\/sony\">Sony<\/a><\/strong> en el mundo de la tecnolog\u00eda m\u00f3vil se construye, principalmente, alrededor de sus potentes sensores de imagen. Al menos, esa es situaci\u00f3n en la actualidad. Y para asegurar su presencia en este departamento por los pr\u00f3ximos a\u00f1os Sony anuncia el Sony IMX500 y el Sony IMX501, los primeros sensores de imagen inteligentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos hablando de dos nuevos sensores de imagen con Inteligencia Artificial integrada lo que les permitir\u00eda comunicarse de forma eficaz con servicios de almacenamiento en la nube. Los Sony IMX500 e IMX501 har\u00e1n las cosas mucho m\u00e1s f\u00e1ciles a la hora de identificar el contenido de cada imagen y c\u00f3mo dicha informaci\u00f3n se procesa y almacena.<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/youtu.be\/20rXEtG4CjQ\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Caracter\u00edsticas de los Sony IMX500 y Sony IMX501<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto el Sony IMX500 como el Sony IMX501 son sensores de imagen de 12,3MP con la capacidad de filmar videos en calidad 4K (hasta 4066 x 2288 p\u00edxeles) a una velocidad de 60fps, videos en calidad Full HD en una velocidad de hasta 240fps y video Full HD con Inteligencia Artificial integrada a una velocidad de hasta 30fps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos sensores tambi\u00e9n reducir\u00e1n la latencia y contribuir\u00e1n notablemente a la protecci\u00f3n de informaci\u00f3n privada al comunicarse directamente con servicios de almacenamiento online. Y lo que es m\u00e1s, sensores inteligentes facilitar\u00e1n el dise\u00f1o y fabricaci\u00f3n de c\u00e1maras inteligentes con los softwares apropiados para explotar estas capacidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sony anuncia el Sony IMX500 y el Sony IMX501 capaces de guardar informaci\u00f3n pertinente a las im\u00e1genes de forma m\u00e1s eficiente y espec\u00edfica. Sin embargo, las diferencias entre el IMX500 y el IMX501 no han quedado claras en su presentaci\u00f3n oficial. Tampoco sabemos exactamente cu\u00e1ndo los estaremos viendo debutar en smartphones u otros dispositivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso es que, una vez m\u00e1s, Sony se encuentra en la vanguardia de los sensores de imagen. Restar\u00e1 por verse si <a href=\"https:\/\/www.smart-gsm.com\/fabricantes\/samsung\">Samsung<\/a> ya est\u00e1 trabajando en sensores ISOCELL equivalentes para competir con los del fabricante japon\u00e9s y si los sensores de imagen ser\u00e1n la pr\u00f3xima tecnolog\u00eda que cambie el paradigma de la fotograf\u00eda m\u00f3vil o no.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Sony IMX500 y Sony IMX501 son los dos primeros sensores de imagen del mundo con inteligencia artificial integrada.<\/p>\n","protected":false},"author":2,"featured_media":83383,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[4133],"tags":[1041],"class_list":["post-83382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sony","tag-sony"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial - SmartGSM - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial - SmartGSM - Blog\" \/>\n<meta property=\"og:description\" content=\"Los Sony IMX500 y Sony IMX501 son los dos primeros sensores de imagen del mundo con inteligencia artificial integrada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartGSM - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T14:24:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T14:24:24+00:00\" \/>\n<meta name=\"author\" content=\"Daniel P\u00e9rez Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/\"},\"author\":{\"name\":\"Daniel P\u00e9rez Alvarez\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\"},\"headline\":\"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial\",\"datePublished\":\"2020-05-14T14:24:07+00:00\",\"dateModified\":\"2020-05-14T14:24:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/\"},\"wordCount\":385,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Sony-IMX500-e-IMX501.jpg\",\"keywords\":[\"Sony\"],\"articleSection\":[\"Sony\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/\",\"name\":\"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial - SmartGSM - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Sony-IMX500-e-IMX501.jpg\",\"datePublished\":\"2020-05-14T14:24:07+00:00\",\"dateModified\":\"2020-05-14T14:24:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Sony-IMX500-e-IMX501.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Sony-IMX500-e-IMX501.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/sony-anuncia-sony-imx500-imx501\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/\",\"name\":\"smartGSM noticias de tel\u00e9fonos\",\"description\":\"smartGSM\",\"alternateName\":\"smartGSM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\",\"name\":\"Daniel P\u00e9rez Alvarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"caption\":\"Daniel P\u00e9rez Alvarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial - SmartGSM - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial - SmartGSM - Blog","og_description":"Los Sony IMX500 y Sony IMX501 son los dos primeros sensores de imagen del mundo con inteligencia artificial integrada.","og_url":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/","og_site_name":"SmartGSM - Blog","article_published_time":"2020-05-14T14:24:07+00:00","article_modified_time":"2020-05-14T14:24:24+00:00","author":"Daniel P\u00e9rez Alvarez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#article","isPartOf":{"@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/"},"author":{"name":"Daniel P\u00e9rez Alvarez","@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da"},"headline":"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial","datePublished":"2020-05-14T14:24:07+00:00","dateModified":"2020-05-14T14:24:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/"},"wordCount":385,"commentCount":0,"image":{"@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2020\/05\/Sony-IMX500-e-IMX501.jpg","keywords":["Sony"],"articleSection":["Sony"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/","url":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/","name":"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial - SmartGSM - Blog","isPartOf":{"@id":"https:\/\/www.smart-gsm.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#primaryimage"},"image":{"@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2020\/05\/Sony-IMX500-e-IMX501.jpg","datePublished":"2020-05-14T14:24:07+00:00","dateModified":"2020-05-14T14:24:24+00:00","author":{"@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da"},"breadcrumb":{"@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#primaryimage","url":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2020\/05\/Sony-IMX500-e-IMX501.jpg","contentUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2020\/05\/Sony-IMX500-e-IMX501.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.smart-gsm.com\/blog\/sony-anuncia-sony-imx500-imx501\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.smart-gsm.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sony presenta los primeros dos sensores de imagen con Inteligencia Artificial"}]},{"@type":"WebSite","@id":"https:\/\/www.smart-gsm.com\/blog\/#website","url":"https:\/\/www.smart-gsm.com\/blog\/","name":"smartGSM noticias de tel\u00e9fonos","description":"smartGSM","alternateName":"smartGSM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smart-gsm.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da","name":"Daniel P\u00e9rez Alvarez","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","caption":"Daniel P\u00e9rez Alvarez"}}]}},"_links":{"self":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts\/83382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/comments?post=83382"}],"version-history":[{"count":0,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts\/83382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/media\/83383"}],"wp:attachment":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/media?parent=83382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/categories?post=83382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/tags?post=83382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}