{"id":69304,"date":"2018-07-25T09:30:45","date_gmt":"2018-07-25T12:30:45","guid":{"rendered":"https:\/\/www.smart-gsm.com\/blog\/?p=69304"},"modified":"2018-07-25T04:32:19","modified_gmt":"2018-07-25T07:32:19","slug":"filtracion-sony-xperia-xz3-renders-video","status":"publish","type":"post","link":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/","title":{"rendered":"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D"},"content":{"rendered":"<p>Sobrados rumores que tienen al Sony Xperia XZ3 por protagonista sit\u00faan su presentaci\u00f3n oficial en la IFA 2018 que suceder\u00e1, como todos los a\u00f1os, en la ciudad de Berl\u00edn, Alemania, temprano durante el mes de septiembre. Estos rumores se ven adem\u00e1s reforzados por la idea de que durante todo el mes de julio no hubo una semana en que no se hubiese filtrado informaci\u00f3n sobre este adviniente\u00a0<em>flagship\u00a0<\/em>de <a href=\"https:\/\/www.smart-gsm.com\/fabricantes\/sony\"><strong>Sony<\/strong><\/a> y esta semana est\u00e1 lejos de ser la excepci\u00f3n. Se filtra el dise\u00f1o del Sony Xperia XZ3 en un video 3D y, por primera vez, el dise\u00f1o dorsal de este smartphone es uno totalmente distinto al que est\u00e1bamos acostumbr\u00e1ndonos a ver.<\/p>\n<p>El sitio\u00a0<em>Compareraja<\/em>, protagonista en 2017 de muchos de los m\u00e1s importantes videos formato CAD adelantando dise\u00f1os de smartphones pr\u00e9mium, public\u00f3 un video 3D del dise\u00f1o frontal y dorsal del Sony Xperia XZ3 y en su contracara vemos una sola lente para su c\u00e1mara principal, en lugar de los regulares dos que esperar\u00edamos de un tel\u00e9fono de su jerarqu\u00eda. Se filtra el dise\u00f1o del Sony Xperia XZ3 en un video 3D y, a continuaci\u00f3n, detallamos la informaci\u00f3n.<\/p>\n<p><!--more--><\/p>\n<p><iframe loading=\"lazy\" title=\"[CompareRaja EXCLUSIVE] Sony Xperia XZ3 Leaked CAD Renders in 360-degree View | CompareRaja\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/IDcYYFW7cT0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Este peque\u00f1o pero contundente video nos muestra un Sony Xperia XZ3 como no lo hab\u00edamos visto hasta ahora: con dise\u00f1o curvado en su cara y contracara, Sony renunciar\u00eda por completo a su pasado ominoso con dise\u00f1o OmniBalance y abrazar\u00eda con fuerza la belleza de sus nuevos dise\u00f1os, priorizando dise\u00f1os con pantalla completa y biseles laterales inexistentes. A\u00fan hay espacio para biseles verticales, pero estos parecieran fundirse casi por completo con el display, naciendo a la vista reci\u00e9n la encenderse el display. En la arista inferior del Sony Xperia XZ3 encontrar\u00edamos un puerto de carga USB tipo C y en la arista superior la bandeja de tarjetas SIM y microSD, pero no hay rastros, tristemente, de ning\u00fan puerto de audio est\u00e1ndar de 3,5mm.<\/p>\n<p>Se filtra el dise\u00f1o del Sony Xperia XZ3 en un video 3D y este video vino acompa\u00f1ado de los rumores de que el Sony Xperia XZ3 contar\u00eda con un display IPS LCD de 5,7 pulgadas con resoluci\u00f3n Full HD+ con ratio de aspecto 18:9 o superior, un procesador Qualcomm Snapdraogn 845, 6GB de memoria RAM y una bater\u00eda de 3450mAh.<\/p>\n<p>En cuanto a la anteriormente rumoreada c\u00e1mara posterior dual pareciera ser que Sony continuar\u00e1 con su tesitura de ofrecer esta pieza de hardware para la variante pr\u00e9mium, es decir, que ser\u00eda el Sony Xperia XZ3 Premium el encargado de lucir una c\u00e1mara dorsal de dos lentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sobrados rumores que tienen al Sony Xperia XZ3 por protagonista sit\u00faan su presentaci\u00f3n oficial en la IFA 2018 que suceder\u00e1, como todos los a\u00f1os, en la ciudad de Berl\u00edn, Alemania,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":69306,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[4133],"tags":[1041,4229],"class_list":["post-69304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sony","tag-sony","tag-sony-xperia-xz3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D - SmartGSM - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D - SmartGSM - Blog\" \/>\n<meta property=\"og:description\" content=\"Sobrados rumores que tienen al Sony Xperia XZ3 por protagonista sit\u00faan su presentaci\u00f3n oficial en la IFA 2018 que suceder\u00e1, como todos los a\u00f1os, en la ciudad de Berl\u00edn, Alemania,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartGSM - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-25T12:30:45+00:00\" \/>\n<meta name=\"author\" content=\"Daniel P\u00e9rez Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/\"},\"author\":{\"name\":\"Daniel P\u00e9rez Alvarez\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\"},\"headline\":\"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D\",\"datePublished\":\"2018-07-25T12:30:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/\"},\"wordCount\":472,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Sony-Xperia-XZ3-2.jpg\",\"keywords\":[\"Sony\",\"Sony Xperia XZ3\"],\"articleSection\":[\"Sony\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/\",\"name\":\"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D - SmartGSM - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Sony-Xperia-XZ3-2.jpg\",\"datePublished\":\"2018-07-25T12:30:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Sony-Xperia-XZ3-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Sony-Xperia-XZ3-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/filtracion-sony-xperia-xz3-renders-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/\",\"name\":\"smartGSM noticias de tel\u00e9fonos\",\"description\":\"smartGSM\",\"alternateName\":\"smartGSM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\",\"name\":\"Daniel P\u00e9rez Alvarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"caption\":\"Daniel P\u00e9rez Alvarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D - SmartGSM - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D - SmartGSM - Blog","og_description":"Sobrados rumores que tienen al Sony Xperia XZ3 por protagonista sit\u00faan su presentaci\u00f3n oficial en la IFA 2018 que suceder\u00e1, como todos los a\u00f1os, en la ciudad de Berl\u00edn, Alemania,...","og_url":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/","og_site_name":"SmartGSM - Blog","article_published_time":"2018-07-25T12:30:45+00:00","author":"Daniel P\u00e9rez Alvarez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#article","isPartOf":{"@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/"},"author":{"name":"Daniel P\u00e9rez Alvarez","@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da"},"headline":"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D","datePublished":"2018-07-25T12:30:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/"},"wordCount":472,"commentCount":0,"image":{"@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2018\/07\/Sony-Xperia-XZ3-2.jpg","keywords":["Sony","Sony Xperia XZ3"],"articleSection":["Sony"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/","url":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/","name":"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D - SmartGSM - Blog","isPartOf":{"@id":"https:\/\/www.smart-gsm.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#primaryimage"},"image":{"@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2018\/07\/Sony-Xperia-XZ3-2.jpg","datePublished":"2018-07-25T12:30:45+00:00","author":{"@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da"},"breadcrumb":{"@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#primaryimage","url":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2018\/07\/Sony-Xperia-XZ3-2.jpg","contentUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2018\/07\/Sony-Xperia-XZ3-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.smart-gsm.com\/blog\/filtracion-sony-xperia-xz3-renders-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.smart-gsm.com\/blog\/"},{"@type":"ListItem","position":2,"name":"As\u00ed se ver\u00eda el Sony Xperia XZ3 en video 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.smart-gsm.com\/blog\/#website","url":"https:\/\/www.smart-gsm.com\/blog\/","name":"smartGSM noticias de tel\u00e9fonos","description":"smartGSM","alternateName":"smartGSM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smart-gsm.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da","name":"Daniel P\u00e9rez Alvarez","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","caption":"Daniel P\u00e9rez Alvarez"}}]}},"_links":{"self":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts\/69304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/comments?post=69304"}],"version-history":[{"count":0,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts\/69304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/media\/69306"}],"wp:attachment":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/media?parent=69304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/categories?post=69304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/tags?post=69304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}