{"id":67858,"date":"2018-05-10T13:37:22","date_gmt":"2018-05-10T16:37:22","guid":{"rendered":"https:\/\/www.smart-gsm.com\/blog\/?p=67858"},"modified":"2018-05-10T13:37:47","modified_gmt":"2018-05-10T16:37:47","slug":"zte-suspension-actividades-comerciales-prohibicion-estadounidense","status":"publish","type":"post","link":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/","title":{"rendered":"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas"},"content":{"rendered":"<p><a href=\"https:\/\/www.smart-gsm.com\/fabricantes\/zte\"><strong>ZTE<\/strong><\/a> hab\u00eda tenido m\u00faltiples episodios conflictivos con la nueva y la vieja administraci\u00f3n del gobierno de los Estados Unidos. En particular, conflictos concernientes a la violaci\u00f3n del tratado de comercio con Ir\u00e1n, actividad que est\u00e1 estrictamente prohibida en la tierra del T\u00edo Sam. Claro, a ZTE no pareci\u00f3 importarle que sus productos estuviesen compuestos por varios componentes fabricados en Norteam\u00e9rica y procedi\u00f3 a distribuir sus smartphones en Ir\u00e1n, gan\u00e1ndole una multa de <a href=\"https:\/\/www.smart-gsm.com\/blog\/zte-pagara-una-multa-de-us892-millones-por-violar-leyes-de-exportaciones\/\">US$900 mil millones<\/a>, primero, y luego, gan\u00e1ndole una <a href=\"https:\/\/www.smart-gsm.com\/blog\/prohibicion-zte-compra-chips-qualcomm-google-play-store\/\">prohibici\u00f3n total<\/a> de compra-venta de productos estadounidense. \u00bfLa consecuencia? A partir del d\u00eda de hoy, ZTE suspende todas sus actividades productivas y comerciales.<\/p>\n<p>Est\u00e1 lejos de saberse a\u00fan si esta situaci\u00f3n cr\u00edtica para ZTE tendr\u00e1 soluci\u00f3n o saberse si el futuro de ZTE tendr\u00e1 que reencarnar en la forma de su segunda marca, Nubia, pero el caso es que ZTE suspende todas sus actividades productivas y comerciales hasta tanto no consiga una modificaci\u00f3n en el fallo del tribunal de comercio estadounidense.<\/p>\n<p><!--more--><\/p>\n<p>Desde hace ya varios d\u00edas, ZTE est\u00e1 intentando apelar al fallo estadounidense que le impide comprar o vender productos all\u00ed fabricados, lo que significa que nada de procesadores Qualcomm ni componentes de ning\u00fan tipo fabricados en la tierra de las bandas y las estrellas. Este bloqueo severo, naturalmente, min\u00f3 por completo las esperanzas de ZTE de continuar existiendo como compa\u00f1\u00eda, y se vio obligada a interrumpir sus actividades comerciales y productivas hasta tanto no obtenga una respuesta a su apelaci\u00f3n.<\/p>\n<p>Actualmente, quienes quieran comprar smartphones en la tienda online oficial de ZTE reciben una notificaci\u00f3n de imposibilidad de completar la operaci\u00f3n y varias tiendas chinas tambi\u00e9n han dejado de vender productos de esta merca. ZTE suspende todas sus actividades productivas y comerciales y, hasta el momento, aunque el futuro de la compa\u00f1\u00eda china es del todo incierto, pr\u00e1cticamente ninguno de los pron\u00f3sticos es optimista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZTE hab\u00eda tenido m\u00faltiples episodios conflictivos con la nueva y la vieja administraci\u00f3n del gobierno de los Estados Unidos. En particular, conflictos concernientes a la violaci\u00f3n del tratado de comercio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":56214,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[4],"tags":[73],"class_list":["post-67858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-zte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas - SmartGSM - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas - SmartGSM - Blog\" \/>\n<meta property=\"og:description\" content=\"ZTE hab\u00eda tenido m\u00faltiples episodios conflictivos con la nueva y la vieja administraci\u00f3n del gobierno de los Estados Unidos. En particular, conflictos concernientes a la violaci\u00f3n del tratado de comercio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartGSM - Blog\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-10T16:37:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-10T16:37:47+00:00\" \/>\n<meta name=\"author\" content=\"Daniel P\u00e9rez Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/\"},\"author\":{\"name\":\"Daniel P\u00e9rez Alvarez\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\"},\"headline\":\"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas\",\"datePublished\":\"2018-05-10T16:37:22+00:00\",\"dateModified\":\"2018-05-10T16:37:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/\"},\"wordCount\":344,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/zte-sign.jpg\",\"keywords\":[\"ZTE\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/\",\"name\":\"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas - SmartGSM - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/zte-sign.jpg\",\"datePublished\":\"2018-05-10T16:37:22+00:00\",\"dateModified\":\"2018-05-10T16:37:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/zte-sign.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/zte-sign.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/\",\"name\":\"smartGSM noticias de tel\u00e9fonos\",\"description\":\"smartGSM\",\"alternateName\":\"smartGSM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smart-gsm.com\\\/blog\\\/#\\\/schema\\\/person\\\/fcacd1fda0b7e21ea34abefb8fdee5da\",\"name\":\"Daniel P\u00e9rez Alvarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g\",\"caption\":\"Daniel P\u00e9rez Alvarez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas - SmartGSM - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas - SmartGSM - Blog","og_description":"ZTE hab\u00eda tenido m\u00faltiples episodios conflictivos con la nueva y la vieja administraci\u00f3n del gobierno de los Estados Unidos. En particular, conflictos concernientes a la violaci\u00f3n del tratado de comercio...","og_url":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/","og_site_name":"SmartGSM - Blog","article_published_time":"2018-05-10T16:37:22+00:00","article_modified_time":"2018-05-10T16:37:47+00:00","author":"Daniel P\u00e9rez Alvarez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#article","isPartOf":{"@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/"},"author":{"name":"Daniel P\u00e9rez Alvarez","@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da"},"headline":"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas","datePublished":"2018-05-10T16:37:22+00:00","dateModified":"2018-05-10T16:37:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/"},"wordCount":344,"commentCount":0,"image":{"@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2016\/11\/zte-sign.jpg","keywords":["ZTE"],"articleSection":["Noticias"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/","url":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/","name":"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas - SmartGSM - Blog","isPartOf":{"@id":"https:\/\/www.smart-gsm.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#primaryimage"},"image":{"@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2016\/11\/zte-sign.jpg","datePublished":"2018-05-10T16:37:22+00:00","dateModified":"2018-05-10T16:37:47+00:00","author":{"@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da"},"breadcrumb":{"@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#primaryimage","url":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2016\/11\/zte-sign.jpg","contentUrl":"https:\/\/www.smart-gsm.com\/blog\/wp-content\/uploads\/2016\/11\/zte-sign.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.smart-gsm.com\/blog\/zte-suspension-actividades-comerciales-prohibicion-estadounidense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.smart-gsm.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ZTE en n\u00fameros rojos: suspende todas sus actividades comerciales y productivas"}]},{"@type":"WebSite","@id":"https:\/\/www.smart-gsm.com\/blog\/#website","url":"https:\/\/www.smart-gsm.com\/blog\/","name":"smartGSM noticias de tel\u00e9fonos","description":"smartGSM","alternateName":"smartGSM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smart-gsm.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/www.smart-gsm.com\/blog\/#\/schema\/person\/fcacd1fda0b7e21ea34abefb8fdee5da","name":"Daniel P\u00e9rez Alvarez","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43a31aba236661f47cd6a1d77bd6cabaacb123e99bc14546b2be829f3369b5dd?s=96&d=mm&r=g","caption":"Daniel P\u00e9rez Alvarez"}}]}},"_links":{"self":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts\/67858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/comments?post=67858"}],"version-history":[{"count":0,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/posts\/67858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/media\/56214"}],"wp:attachment":[{"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/media?parent=67858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/categories?post=67858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smart-gsm.com\/blog\/wp-json\/wp\/v2\/tags?post=67858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}